{"id":1977,"date":"2016-10-16T15:30:35","date_gmt":"2016-10-16T15:30:35","guid":{"rendered":"http:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26.jpg"},"modified":"2016-10-16T15:30:35","modified_gmt":"2016-10-16T15:30:35","slug":"1-26","status":"inherit","type":"attachment","link":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/galerie\/ausstellung-2008\/1-26\/","title":{"rendered":"1-26"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1977","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-300x225.jpg 300w, https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-768x576.jpg 768w, https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-1024x768.jpg 1024w, https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1536,"file":"2016\/04\/1-26.jpg","sizes":{"thumbnail":{"file":"1-26-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-150x150.jpg"},"medium":{"file":"1-26-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-300x225.jpg"},"medium_large":{"file":"1-26-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-768x576.jpg"},"large":{"file":"1-26-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26-1024x768.jpg"},"full":{"file":"1-26.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon DIGITAL IXUS v3","caption":"","created_timestamp":"1226768168","copyright":"","focal_length":"5.40625","iso":"0","shutter_speed":"0.0166666666667","title":"","orientation":"1","keywords":[]}},"post":286,"source_url":"https:\/\/www.thesamplers.de\/wordpress\/wp-content\/uploads\/2016\/04\/1-26.jpg","filename":"1-26.jpg","filesize":1335515,"_links":{"self":[{"href":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/1977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=1977"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":286,"href":"https:\/\/www.thesamplers.de\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}